{"id":24151,"date":"2024-08-23T14:50:24","date_gmt":"2024-08-23T18:50:24","guid":{"rendered":"https:\/\/www.leaf.ca\/?post_type=news&#038;p=24151"},"modified":"2024-08-29T14:52:23","modified_gmt":"2024-08-29T18:52:23","slug":"conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois","status":"publish","type":"news","link":"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/","title":{"rendered":"Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (contrat de 30 MOIS)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>APER\u00c7U DU POSTE<\/strong><\/h2>\n\n\n\n<p>Le FAEJ est \u00e0 la recherche d\u2019un\u00b7e conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (\u00c9JP) qui jouera un r\u00f4le essentiel dans les efforts de collecte de fonds pour faire progresser l\u2019\u00e9galit\u00e9 des genres au Canada. Il s\u2019agit d\u2019un poste contractuel de 30 mois d\u00e9butant en octobre 2024.<\/p>\n\n\n\n<p>Il s\u2019agit d\u2019un poste hybride; le\/la candidat\u00b7e retenu\u00b7e devra travailler au moins deux jours par semaine depuis les bureaux du FAEJ au centre-ville de Toronto.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>QUI NOUS SOMMES<\/strong><\/h2>\n\n\n\n<p>Le Fonds d\u2019action et d\u2019\u00e9ducation juridique pour les femmes (FAEJ) est un organisme national sans but lucratif vou\u00e9 \u00e0 faire avancer les droits \u00e0 l\u2019\u00e9galit\u00e9 des femmes, des filles ainsi que des personnes transgenres et non&nbsp;binaires au Canada, au moyen de litiges et d\u2019initiatives de r\u00e9forme du droit et d\u2019\u00e9ducation juridique du public. Depuis plus de 35&nbsp;ans, le travail du FAEJ influence l\u2019\u00e9volution des principes constitutionnels d\u2019\u00e9galit\u00e9 au Canada et a fait une diff\u00e9rence importante dans la vie quotidienne des femmes, des filles et des personnes affect\u00e9es par la discrimination fond\u00e9e sur le genre \u00e0 travers le pays.<\/p>\n\n\n\n<p>Le bureau du FAEJ est situ\u00e9 au centre-ville de Toronto, ou Tkar\u00f3n:to, nom mohawk qui signifie \u00ab&nbsp;l\u2019endroit dans l\u2019eau o\u00f9 se dressent des arbres&nbsp;\u00bb. Ce territoire est r\u00e9gi par le Pacte de la ceinture wampum du bol \u00e0 une seule cuill\u00e8re, un accord de paix entre les nations Anishinaabes, les Haudenosaunees, les Wendats et d\u2019autres nations alli\u00e9es.<\/p>\n\n\n\n<p>Le FAEJ compte \u00e9galement onze filiales membres dirig\u00e9es par des b\u00e9n\u00e9voles partout au pays, qui r\u00e9alisent des programmes d\u2019\u00e9ducation du public aupr\u00e8s des jeunes, tiennent des \u00e9v\u00e9nements sur l\u2019\u00e9galit\u00e9 des genres dans leurs communaut\u00e9s et participent \u00e0 des initiatives de r\u00e9forme du droit au palier local.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>QUI VOUS \u00caTES<\/strong><\/h2>\n\n\n\n<p>Les enjeux f\u00e9ministes actuels et l\u2019\u00e9ducation juridique du public vous passionnent. Vous avez de l\u2019exp\u00e9rience en \u00e9ducation du public, id\u00e9alement sur des questions juridiques, et en travail aupr\u00e8s de jeunes du secondaire et du postsecondaire. Vous \u00eates stimul\u00e9\u00b7e par le travail d\u2019\u00e9quipe et la collaboration avec des b\u00e9n\u00e9voles de partout au Canada qui ont \u00e0 c\u0153ur l\u2019\u00e9galit\u00e9 des genres. Vous apportez une perspective f\u00e9ministe intersectionnelle \u00e0 votre travail, notamment dans votre analyse, vos collaborations et votre style de communication.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PRINCIPALES RESPONSABILIT<\/strong>\u00c9<strong>S DU POSTE<\/strong><\/h2>\n\n\n\n<p>Le ou la conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (\u00c9JP) concevra et \u00e9valuera l\u2019animation des initiatives du FAEJ en la mati\u00e8re, tout en y prenant part; renforcera la capacit\u00e9 des filiales du FAEJ \u00e0 fournir une \u00c9JP \u00e0 travers le pays; et apportera \u00e0 l\u2019organisme un soutien important dans ce domaine plus g\u00e9n\u00e9ralement.<\/p>\n\n\n\n<p>En particulier, le ou la conseiller\u00b7\u00e8re en \u00c9JP assumera les responsabilit\u00e9s suivantes&nbsp;:<\/p>\n\n\n\n<p>Conception, gestion et \u00e9valuation des programmes d\u2019\u00c9JP<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Travailler avec la directrice ex\u00e9cutive et conseill\u00e8re g\u00e9n\u00e9rale du FAEJ au d\u00e9veloppement d\u2019un plan annuel d\u2019\u00c9JP.<\/li>\n\n\n\n<li>Mettre \u00e0 jour et maintenir le programme et le mat\u00e9riel d\u2019\u00e9ducation existants, pour toutes les initiatives d\u2019\u00e9ducation, en consultation avec les filiales b\u00e9n\u00e9voles, des organismes jeunesse, des jeunes, le Comit\u00e9 de l\u2019\u00e9ducation du FAEJ, et le prochain projet du FAEJ sur l\u2019\u00e9conomie des soins.<\/li>\n\n\n\n<li>Cr\u00e9er de nouveaux programmes d\u2019\u00e9ducation et \u00e9l\u00e9ments de contenu, notamment pour le prochain projet du FAEJ sur l\u2019\u00e9conomie des soins&nbsp;<\/li>\n\n\n\n<li>Consulter les membres de l\u2019\u00e9quipe juridique du FAEJ pour assurer l\u2019exactitude et l\u2019actualit\u00e9 des informations juridiques des programmes d\u2019\u00e9ducation.<\/li>\n\n\n\n<li>D\u00e9velopper les formules pour la pr\u00e9sentation en&nbsp;ligne des ateliers de programmes d\u2019\u00c9JP du FAEJ.<\/li>\n\n\n\n<li>Diriger l\u2019\u00e9laboration et la r\u00e9alisation de l\u2019\u00e9valuation des programmes d\u2019\u00c9JP<\/li>\n\n\n\n<li>Faire \u00e9tat des r\u00e9sultats de l\u2019\u00e9valuation \u00e0 la directrice ex\u00e9cutive et conseill\u00e8re g\u00e9n\u00e9rale du FAEJ ainsi qu\u2019aux autres membres du personnel et du conseil d\u2019administration, selon les besoins<\/li>\n<\/ul>\n\n\n\n<p>MISE EN \u0152UVRE DE L\u2019\u00c9JP PAR LES FILIALES<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>G\u00e9rer les programmes d\u2019\u00c9JP de l\u2019organisme et les directeur\u00b7trice\u00b7s des filiales qui s\u2019occupent principalement de la mise en \u0153uvre de ces programmes<\/li>\n\n\n\n<li>Soutenir les filiales du FAEJ et renforcer leur capacit\u00e9 \u00e0 mettre en \u0153uvre les programmes d\u2019\u00c9JP du FAEJ&nbsp;<\/li>\n\n\n\n<li>Aider les filiales \u00e0 former des animateur\u00b7trice\u00b7s de programmes d\u2019\u00e9ducation, notamment en fournissant le contenu de cette formation et en offrant aux animateur\u00b7trice\u00b7s les informations et le mat\u00e9riel n\u00e9cessaires.<\/li>\n\n\n\n<li>Collaborer avec la coordonnatrice de bureau et des relations avec les filiales \u00e0 d\u00e9velopper et \u00e0 mettre en \u0153uvre un syst\u00e8me de suivi et de soutien pour les filiales, les animateur\u00b7trice\u00b7s d\u2019ateliers et les autres b\u00e9n\u00e9voles du FAEJ<\/li>\n<\/ul>\n\n\n\n<p>SOUTIEN DU FAEJ \u00c0 L\u2019\u00c9CHELLE NATIONALE<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Animer des s\u00e9ances d\u2019\u00e9ducation juridique du public et \u00eatre porte-parole sur des sujets li\u00e9s au travail du FAEJ en mati\u00e8re d\u2019\u00c9JP, selon les besoins<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Collaborer avec le personnel du FAEJ pour organiser des panels et des webinaires d\u2019\u00c9JP, selon les besoins.<\/li>\n\n\n\n<li>Collaborer avec la conseill\u00e8re en communication et plaidoyer pour faire en sorte que les informations et les documents relatifs \u00e0 l\u2019\u00c9JP soient accessibles en&nbsp;ligne, notamment sur le site Internet du FAEJ ainsi que via la liste de diffusion \u00e9lectronique et dans les m\u00e9dias sociaux.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>QUALIFICATIONS ET CARACT\u00c9RISTIQUES ESSENTIALLES CHEZ LES CANDIDAT\u00b7E\u00b7<\/strong>S<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dipl\u00f4me d\u2019\u00e9tudes postsecondaires ou exp\u00e9rience \u00e9quivalente dans le domaine de l\u2019\u00e9ducation, des sciences sociales, des sciences humaines et\/ou un domaine connexe.<\/li>\n\n\n\n<li>Expertise de communication en langage simple.<\/li>\n\n\n\n<li>Exp\u00e9rience en conception et\/ou animation d\u2019ateliers d\u2019\u00c9JP.<\/li>\n\n\n\n<li>Exp\u00e9rience en conception et\/ou animation d\u2019ateliers \u00e9ducatifs pour des jeunes (\u00e9cole secondaire, coll\u00e8ge ou universit\u00e9).<\/li>\n\n\n\n<li>Exp\u00e9rience de travail avec des b\u00e9n\u00e9voles.<\/li>\n\n\n\n<li>Une compr\u00e9hension de la nature genr\u00e9e et des r\u00e9alit\u00e9s du travail de soins.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Excellentes habilet\u00e9s de communication \u00e9crite et orale.<\/li>\n\n\n\n<li>Capacit\u00e9 \u00e0 travailler de fa\u00e7on ind\u00e9pendante et en \u00e9quipe.<\/li>\n\n\n\n<li>Exp\u00e9rience en gestion de projets; id\u00e9alement de multiples projets simultan\u00e9s.<\/li>\n\n\n\n<li>Engagement manifeste \u00e0 l\u2019\u00e9gard du f\u00e9minisme intersectionnel et\/ou de la justice sociale, y compris une exp\u00e9rience au sein de mouvements\/organismes de justice sociale.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>LE\/LA CANDIDAT\u00b7E ID\u00c9AL\u00b7E AURAIT PAR AILLEURS&nbsp;:<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une formation acad\u00e9mique en droit et\/ou en \u00e9ducation<\/li>\n\n\n\n<li>De l\u2019exp\u00e9rience en \u00e9valuation de programme<\/li>\n\n\n\n<li>De l\u2019exp\u00e9rience en conception et\/ou en animation d\u2019ateliers d\u2019\u00c9JP en&nbsp;ligne<\/li>\n\n\n\n<li>De l\u2019exp\u00e9rience en d\u00e9veloppement et en pr\u00e9sentation de mod\u00e8les de \u00ab&nbsp;formation de formateur\u00b7trice\u00b7s&nbsp;\u00bb<\/li>\n\n\n\n<li>Une ma\u00eetrise du fran\u00e7ais<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>R\u00c9MUN\u00c9RATION ET AVANTAGES SOCIAUX<\/strong><\/h2>\n\n\n\n<p>Il s\u2019agit d\u2019un poste contractuel \u00e0 temps plein de deux ans avec possibilit\u00e9 de prolongation. Le\/la candidat\u00b7e retenu\u00b7e recevra un salaire de 72&nbsp;000 \u00e0 80&nbsp;000&nbsp;$ de m\u00eame que des avantages additionnels incluant trois semaines de vacances d\u00e8s la premi\u00e8re ann\u00e9e, trois semaines de cong\u00e9s de maladie pay\u00e9s, une semaine de cong\u00e9s pay\u00e9s pour les aidant\u00b7e\u00b7s, trois jours de cong\u00e9s personnels pay\u00e9s, une semaine de fermeture des bureaux pendant les vacances de d\u00e9cembre, un budget annuel pour le d\u00e9veloppement professionnel continu et l\u2019inscription au r\u00e9gime d\u2019avantages sociaux complet du FAEJ, qui comprend des prestations de sant\u00e9 et de soins dentaires. Le FAEJ organise \u00e9galement des c\u00e9l\u00e9brations d\u2019anniversaires des membres du personnel et des d\u00eeners d\u2019\u00e9quipe mensuels avec traiteur.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">COMMENT POSTULER<\/h2>\n\n\n\n<p>Le FAEJ reconna\u00eet que des obstacles structurels influencent les exp\u00e9riences, les qualifications et le sentiment de capacit\u00e9. Nous encourageons les personnes \u00e0 poser leur candidature m\u00eame si elles pensent que le poste pourrait \u00eatre trop exigeant pour elles. Le FAEJ s\u2019engage \u00e0 soutenir l\u2019agent\u00b7e de d\u00e9veloppement par le biais d\u2019une orientation, d\u2019une formation et d\u2019un mentorat continu.<\/p>\n\n\n\n<p>Le FAEJ encourage les candidatures de personnes repr\u00e9sentant la diversit\u00e9 de nos communaut\u00e9s. Nous encourageons fortement les candidatures de personnes noires, autochtones et racis\u00e9es ainsi que de nouveaux\u00b7elles arrivant\u00b7e\u00b7s, personnes de genres divers et membres d\u2019autres groupes en qu\u00eate d\u2019\u00e9quit\u00e9. Si vous vous sentez \u00e0 l\u2019aise de le faire, merci d\u2019indiquer dans votre lettre de pr\u00e9sentation si vous vous consid\u00e9rez comme faisant partie d\u2019un groupe en qu\u00eate d\u2019\u00e9quit\u00e9.&nbsp;<\/p>\n\n\n\n<p>Le FAEJ accueille et encourage les candidatures de personnes handicap\u00e9es \u00e0 tous les postes \u00e0 pourvoir. Dans la mesure du possible, des am\u00e9nagements seront fournis sur demande aux candidat\u00b7e\u00b7s qui prendront part \u00e0 toutes les \u00e9tapes du processus de s\u00e9lection.&nbsp;<\/p>\n\n\n\n<p><strong>Pour postuler, veuillez joindre les documents suivants dans un seul fichier PDF et l\u2019envoyer \u00e0&nbsp;<\/strong><a href=\"mailto:hiring@leaf.ca\"><strong>hiringcommittee@leaf.ca<\/strong><\/a><strong>&nbsp;:<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Votre lettre de pr\u00e9sentation&nbsp;<\/li>\n\n\n\n<li>Votre curriculum vit\u00e6&nbsp;<\/li>\n\n\n\n<li>Une liste de trois r\u00e9f\u00e9rences (avec le nom, le num\u00e9ro de t\u00e9l\u00e9phone et l\u2019adresse courriel de chaque personne contact)<\/li>\n<\/ul>\n\n\n\n<p>Dans la ligne d\u2019objet de votre candidature par courriel, inscrivez \u00ab&nbsp;Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public&nbsp;\u00bb.&nbsp;<\/p>\n\n\n\n<p>Veuillez adresser votre candidature au Comit\u00e9 d\u2019embauche. Dans votre lettre de pr\u00e9sentation, expliquez pourquoi vous souhaitez travailler avec le FAEJ et pourquoi vous \u00eates qualifi\u00e9\u00b7e pour le poste compte tenu des t\u00e2ches, responsabilit\u00e9s, qualifications et exp\u00e9riences susmentionn\u00e9es. Pri\u00e8re de ne pas soumettre de candidatures multiples ou de documents suppl\u00e9mentaires.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9CH\u00c9ANCIER D&rsquo;EMBAUCHE<\/h2>\n\n\n\n<p>Les candidatures pour ce poste seront accept\u00e9es jusqu\u2019\u00e0 23&nbsp;h&nbsp;59 (heure de l\u2019Est) le 4 septembre&nbsp;juin&nbsp;2024. Les entrevues se tiendront au cours de la semaine du 16 septembre 2024. Les entrevues auront lieu virtuellement. La date id\u00e9ale d\u2019entr\u00e9e en fonction pour ce poste est le 7 octobre 2024.<\/p>\n\n\n\n<p>Nous remercions tou\u00b7te\u00b7s les candidat\u00b7e\u00b7s pour leur int\u00e9r\u00eat, mais nous ne communiquerons qu\u2019avec les candidat\u00b7e\u00b7s que nous souhaitons voir en entrevue.&nbsp;<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":true},"categories":[],"tags":[],"class_list":["post-24151","news","type-news","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (contrat de 30 MOIS) - LEAF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nous recrutons!\" \/>\n<meta property=\"og:description\" content=\"APER\u00c7U DU POSTE Le FAEJ est \u00e0 la recherche d\u2019un\u00b7e conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (\u00c9JP) qui jouera un r\u00f4le essentiel dans les efforts de collecte de fonds pour faire progresser l\u2019\u00e9galit\u00e9 des genres au Canada. Il s\u2019agit d\u2019un poste contractuel de 30 mois d\u00e9butant en octobre 2024. Il s\u2019agit d\u2019un poste hybride; le\/la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/\" \/>\n<meta property=\"og:site_name\" content=\"LEAF\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T18:52:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leaf.ca\/wp-content\/uploads\/2024\/08\/Hiring-Banner-FR-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nous recrutons!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.leaf.ca\/wp-content\/uploads\/2024\/08\/Hiring-Banner-FR.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/news\\\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\\\/\",\"url\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/news\\\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\\\/\",\"name\":\"Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (contrat de 30 MOIS) - LEAF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/#website\"},\"datePublished\":\"2024-08-23T18:50:24+00:00\",\"dateModified\":\"2024-08-29T18:52:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/news\\\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/news\\\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/news\\\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (contrat de 30 MOIS)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/\",\"name\":\"LEAF\",\"description\":\"Women&#039;s Legal Education and Action Fund\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/#organization\",\"name\":\"LEAF\",\"url\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.leaf.ca\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/LEAF_FAEJ_hz_names_colour_rgb.svg\",\"contentUrl\":\"https:\\\/\\\/www.leaf.ca\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/LEAF_FAEJ_hz_names_colour_rgb.svg\",\"width\":612,\"height\":110,\"caption\":\"LEAF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.leaf.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (contrat de 30 MOIS) - LEAF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/","og_locale":"fr_FR","og_type":"article","og_title":"Nous recrutons!","og_description":"APER\u00c7U DU POSTE Le FAEJ est \u00e0 la recherche d\u2019un\u00b7e conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (\u00c9JP) qui jouera un r\u00f4le essentiel dans les efforts de collecte de fonds pour faire progresser l\u2019\u00e9galit\u00e9 des genres au Canada. Il s\u2019agit d\u2019un poste contractuel de 30 mois d\u00e9butant en octobre 2024. Il s\u2019agit d\u2019un poste hybride; le\/la [&hellip;]","og_url":"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/","og_site_name":"LEAF","article_modified_time":"2024-08-29T18:52:23+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.leaf.ca\/wp-content\/uploads\/2024\/08\/Hiring-Banner-FR-1024x576.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Nous recrutons!","twitter_image":"https:\/\/www.leaf.ca\/wp-content\/uploads\/2024\/08\/Hiring-Banner-FR.png","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/","url":"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/","name":"Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (contrat de 30 MOIS) - LEAF","isPartOf":{"@id":"https:\/\/www.leaf.ca\/fr\/#website"},"datePublished":"2024-08-23T18:50:24+00:00","dateModified":"2024-08-29T18:52:23+00:00","breadcrumb":{"@id":"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leaf.ca\/fr\/news\/conseiller%c2%b7ere-en-education-juridique-du-public-contrat-de-30-mois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leaf.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.leaf.ca\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Conseiller\u00b7\u00e8re en \u00e9ducation juridique du public (contrat de 30 MOIS)"}]},{"@type":"WebSite","@id":"https:\/\/www.leaf.ca\/fr\/#website","url":"https:\/\/www.leaf.ca\/fr\/","name":"LEAF","description":"Women&#039;s Legal Education and Action Fund","publisher":{"@id":"https:\/\/www.leaf.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leaf.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.leaf.ca\/fr\/#organization","name":"LEAF","url":"https:\/\/www.leaf.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.leaf.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.leaf.ca\/wp-content\/uploads\/2020\/09\/LEAF_FAEJ_hz_names_colour_rgb.svg","contentUrl":"https:\/\/www.leaf.ca\/wp-content\/uploads\/2020\/09\/LEAF_FAEJ_hz_names_colour_rgb.svg","width":612,"height":110,"caption":"LEAF"},"image":{"@id":"https:\/\/www.leaf.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.leaf.ca\/fr\/wp-json\/wp\/v2\/news\/24151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leaf.ca\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.leaf.ca\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/www.leaf.ca\/fr\/wp-json\/wp\/v2\/media?parent=24151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leaf.ca\/fr\/wp-json\/wp\/v2\/categories?post=24151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leaf.ca\/fr\/wp-json\/wp\/v2\/tags?post=24151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}